{"id":122,"count":0,"description":"","link":"https:\/\/duett.es\/es\/cocina\/conservacion-de-alimentos\/","name":"Conservaci\u00f3n de alimentos","slug":"conservacion-de-alimentos","taxonomy":"product_cat","parent":37,"meta":[],"menu_order":0,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conservaci\u00f3n de alimentos - Duett<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/duett.es\/es\/cocina\/conservacion-de-alimentos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conservaci\u00f3n de alimentos - Duett\" \/>\n<meta property=\"og:url\" content=\"https:\/\/duett.es\/es\/cocina\/conservacion-de-alimentos\/\" \/>\n<meta property=\"og:site_name\" content=\"Duett\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/duett.es\\\/es\\\/cocina\\\/conservacion-de-alimentos\\\/\",\"url\":\"https:\\\/\\\/duett.es\\\/es\\\/cocina\\\/conservacion-de-alimentos\\\/\",\"name\":\"Conservaci\u00f3n de alimentos - Duett\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/duett.es\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/duett.es\\\/es\\\/cocina\\\/conservacion-de-alimentos\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/duett.es\\\/es\\\/cocina\\\/conservacion-de-alimentos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/duett.es\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cocina\",\"item\":\"https:\\\/\\\/duett.es\\\/es\\\/cocina\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Conservaci\u00f3n de alimentos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/duett.es\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/duett.es\\\/es\\\/\",\"name\":\"Duett\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/duett.es\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/duett.es\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/duett.es\\\/es\\\/#organization\",\"name\":\"Duett\",\"url\":\"https:\\\/\\\/duett.es\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/duett.es\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/duett.es\\\/wp-content\\\/uploads\\\/logo-duett.svg\",\"contentUrl\":\"https:\\\/\\\/duett.es\\\/wp-content\\\/uploads\\\/logo-duett.svg\",\"width\":122,\"height\":34,\"caption\":\"Duett\"},\"image\":{\"@id\":\"https:\\\/\\\/duett.es\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conservaci\u00f3n de alimentos - Duett","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/duett.es\/es\/cocina\/conservacion-de-alimentos\/","og_locale":"es_ES","og_type":"article","og_title":"Conservaci\u00f3n de alimentos - Duett","og_url":"https:\/\/duett.es\/es\/cocina\/conservacion-de-alimentos\/","og_site_name":"Duett","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/duett.es\/es\/cocina\/conservacion-de-alimentos\/","url":"https:\/\/duett.es\/es\/cocina\/conservacion-de-alimentos\/","name":"Conservaci\u00f3n de alimentos - Duett","isPartOf":{"@id":"https:\/\/duett.es\/es\/#website"},"breadcrumb":{"@id":"https:\/\/duett.es\/es\/cocina\/conservacion-de-alimentos\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/duett.es\/es\/cocina\/conservacion-de-alimentos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/duett.es\/es\/"},{"@type":"ListItem","position":2,"name":"Cocina","item":"https:\/\/duett.es\/es\/cocina\/"},{"@type":"ListItem","position":3,"name":"Conservaci\u00f3n de alimentos"}]},{"@type":"WebSite","@id":"https:\/\/duett.es\/es\/#website","url":"https:\/\/duett.es\/es\/","name":"Duett","description":"","publisher":{"@id":"https:\/\/duett.es\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/duett.es\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/duett.es\/es\/#organization","name":"Duett","url":"https:\/\/duett.es\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/duett.es\/es\/#\/schema\/logo\/image\/","url":"https:\/\/duett.es\/wp-content\/uploads\/logo-duett.svg","contentUrl":"https:\/\/duett.es\/wp-content\/uploads\/logo-duett.svg","width":122,"height":34,"caption":"Duett"},"image":{"@id":"https:\/\/duett.es\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/duett.es\/es\/wp-json\/wp\/v2\/product_cat\/122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/duett.es\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/duett.es\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/duett.es\/es\/wp-json\/wp\/v2\/product_cat\/37"}],"wp:post_type":[{"href":"https:\/\/duett.es\/es\/wp-json\/wp\/v2\/product?product_cat=122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}